{"id":20320,"date":"2026-02-23T14:57:43","date_gmt":"2026-02-23T13:57:43","guid":{"rendered":"https:\/\/i2cat.net\/?p=20320"},"modified":"2026-03-16T09:41:03","modified_gmt":"2026-03-16T08:41:03","slug":"6gstarlab-mwc-barcelona-2026","status":"publish","type":"post","link":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/","title":{"rendered":"El 6GStarLab, el primer laboratori 6G europeu a l&#8217;espai, al MWC Barcelona 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Sota el claim \u00abBringing the 6G Ecosystem to Zero Gravity\u00bb, i2CAT va aterrar al MWC Barcelona 2026 per posar a l&#8217;abast de l&#8217;ecosistema tecnol\u00f2gic i de recerca el 6GStarLab, el primer sat\u00e8l\u00b7lit de recerca 6G en \u00f2rbita baixa d&#8217;Europa.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del 2 al 5 de mar\u00e7, i2CAT va ser al pavell\u00f3 de la <strong>Generalitat de Catalunya<\/strong> del MWC Barcelona. En aquesta 20a edici\u00f3 del congr\u00e9s, el nostre objectiu era clar: facilitar que tant pimes com grans corporacions i centres de recerca puguin liderar la propera generaci\u00f3 de connectivitat sense dependre de tecnologies externes, utilitzant una infraestructura dissenyada i fabricada \u00edntegrament a Catalunya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Recerca \u00abKm 0\u00bb per assolir la sobirania tecnol\u00f2gica<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <a href=\"https:\/\/i2cat.net\/ca\/llancament-6gstarlab\/\"><strong>6GStarLab<\/strong><\/a> no \u00e9s nom\u00e9s una fita tecnol\u00f2gica; \u00e9s un <strong>laboratori obert dissenyat per democratitzar l&#8217;acc\u00e9s a l&#8217;espai<\/strong>. Mitjan\u00e7ant aquest banc de proves en \u00f2rbita baixa (LEO), oferim a la ind\u00fastria un entorn real per validar tecnologies cr\u00edtiques que definiran la d\u00e8cada vinent.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Day 1 at #MWC26 | The First 6G Laboratory in Orbit | i2CAT #shorts\" width=\"540\" height=\"960\" src=\"https:\/\/www.youtube.com\/embed\/ehIo61srwGE?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/i2cat.net\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cat\u00e0leg de serveis i experiments<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquest MWC presentem un ventall de possibilitats perqu\u00e8 puguis portar la teva innovaci\u00f3 al seg\u00fcent nivell:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Validaci\u00f3 de protocols 6G:<\/strong> experimenta amb noves capes f\u00edsiques i d&#8217;enlla\u00e7 en un entorn orbital real.<\/li>\n\n\n\n<li><strong>Edge Computing espacial:<\/strong> testeja el processament de dades en \u00f2rbita per reduir la lat\u00e8ncia en les teves aplicacions.<\/li>\n\n\n\n<li><strong>Comunicacions l\u00e0ser:<\/strong> verifica l&#8217;efici\u00e8ncia de l&#8217;enlla\u00e7 \u00f2ptic espai-terra-espai per a un intercanvi de dades massiu i segur.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L\u2019era de la qu\u00e0ntica, m\u00e9s a prop<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"986\" height=\"555\" src=\"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/04A-i2CAT-OGS-MWC26-CAT-986x555.jpg\" alt=\"Infografia dels components de l'estaci\u00f3 \u00f2ptica de M\u00f3ra la Nova\" class=\"wp-image-20371\" srcset=\"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/04A-i2CAT-OGS-MWC26-CAT-986x555.jpg 986w, https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/04A-i2CAT-OGS-MWC26-CAT-768x432.jpg 768w, https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/04A-i2CAT-OGS-MWC26-CAT-1536x864.jpg 1536w, https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/04A-i2CAT-OGS-MWC26-CAT-480x270.jpg 480w, https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/04A-i2CAT-OGS-MWC26-CAT.jpg 1920w\" sizes=\"auto, (max-width: 986px) 100vw, 986px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A l\u2019<strong>estaci\u00f3 terrestre<\/strong> que controlar\u00e0 els experiments del 6GStarLab, situada a M\u00f3ra la Nova, caracteritzem par\u00e0metres com les turbul\u00e8ncies o la nuvolositat per mapejar l\u2019enlla\u00e7 \u00f2ptic. Amb aquest model, al laboratori de comunicacions qu\u00e0ntiques d\u2019i2CAT de la nostra seu del Pier01 de Barcelona, podem <strong>simular l&#8217;atmosfera i dissenyar els protocols necessaris per intercanviar claus qu\u00e0ntiques<\/strong> de la manera m\u00e9s efica\u00e7 possible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les activitats d\u2019i2CAT al MWC 2026<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nostra <strong>spin-off <\/strong><a href=\"https:\/\/www.volum.tech\/\"><strong>Volum Technologies<\/strong><\/a> <strong>va aterrar al <\/strong><a href=\"https:\/\/www.4yfn.com\/\"><strong>4YFN<\/strong><\/a> per presentar les seves solucions de comunicaci\u00f3 hologr\u00e0fica i volum\u00e8trica en temps real, dissenyades per transformar la interacci\u00f3 digital. Les persones que van visitar l&#8217;estand van poder experimentar com la tecnologia 3D millora la connexi\u00f3 humana i obre noves oportunitats per a la ind\u00fastria immersiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a part de la tercera convocat\u00f2ria oberta de la iniciativa SNS <a href=\"https:\/\/6g-sandbox.eu\/\"><strong>6G-SANDBOX<\/strong><\/a>, l&#8217;\u00faltim aven\u00e7 en telecomunicacions sostenibles es va presentar a l&#8217;estand de <strong>Keysight Technologies<\/strong>. Es tracta d\u2019una demostraci\u00f3 en v\u00eddeo dels resultats del <strong>projecte ECO-RAN<\/strong>, una soluci\u00f3 per a O-RAN basada en IA que aborda un dels majors reptes de la ind\u00fastria: el consum d&#8217;energia. Utilitzant dades reals d&#8217;operadors, la soluci\u00f3 optimitza la gesti\u00f3 de la xarxa per reduir el consum d&#8217;energia sense afectar la qualitat del servei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Els projectes del <strong>programa RETECH<\/strong> tamb\u00e9 van tenir pres\u00e8ncia al congr\u00e9s. RETECH est\u00e0 promogut per la Generalitat de Catalunya i el Ministerio de Transformaci\u00f3n Digital y Funci\u00f3n P\u00fablica amb fons NextGenerationEU. El pavell\u00f3 de la Generalitat de Catalunya va mostrar <strong>ROBOCAT<\/strong>, un robot assistencial desenvolupat per l&#8217;Institut de Rob\u00f2tica i Inform\u00e0tica Industrial de la UPC, que utilitza sensors ambientals desenvolupats pel nostre personal investigador.<br>Al Pavell\u00f3 d&#8217;Espanya es va presentar <strong>MULTIMINDED<\/strong>, un projecte en qu\u00e8 col\u00b7laborem amb SIRT per crear un bess\u00f3 digital inclusiu per a tots els ciutadans.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"986\" height=\"657\" src=\"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/2359image1773231372.973694o-986x657.jpg\" alt=\"\" class=\"wp-image-20499\" srcset=\"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/2359image1773231372.973694o-986x657.jpg 986w, https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/2359image1773231372.973694o-768x512.jpg 768w, https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/2359image1773231372.973694o-1536x1024.jpg 1536w, https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/2359image1773231372.973694o.jpg 2048w\" sizes=\"auto, (max-width: 986px) 100vw, 986px\" \/><figcaption class=\"wp-element-caption\">Presentaci\u00f3 del projecte MULTIMINDED durant el MWC 2026<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><strong>No et perdis els millors moments del MWC 2026! <a href=\"https:\/\/www.flickr.com\/photos\/i2cat\/albums\/72177720322561244\/\">Consulta totes les fotografies a la nostra p\u00e0gina de Flickr.<\/a><\/strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Badge de missi\u00f3 del laboratori en \u00f2rbita 6GStarLab<\/p>\n","protected":false},"author":5,"featured_media":20434,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-20320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-ca","area-space-communications","group-space-communications","collection-corporate"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El 6GStarLab, el primer laboratori 6G europeu a l&#039;espai, al MWC Barcelona 2026 - i2CAT Research Centre<\/title>\n<meta name=\"description\" content=\"i2CAT va aterrar al MWC Barcelona 2026 per posar a l&#039;abast de l&#039;ecosistema tecnol\u00f2gic i de recerca el 6GStarLab.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El 6GStarLab, el primer laboratori 6G europeu a l&#039;espai, al MWC Barcelona 2026 - i2CAT Research Centre\" \/>\n<meta property=\"og:description\" content=\"i2CAT va aterrar al MWC Barcelona 2026 per posar a l&#039;abast de l&#039;ecosistema tecnol\u00f2gic i de recerca el 6GStarLab.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"i2CAT Research Centre\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-23T13:57:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-16T08:41:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/7063_1DLL_017-scaled-e1772803447594.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1708\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00edriam Castillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/\"},\"author\":{\"name\":\"M\u00edriam Castillo\",\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/#\\\/schema\\\/person\\\/904ec3612e2fc19f33f02806e8f7f81d\"},\"headline\":\"El 6GStarLab, el primer laboratori 6G europeu a l&#8217;espai, al MWC Barcelona 2026\",\"datePublished\":\"2026-02-23T13:57:43+00:00\",\"dateModified\":\"2026-03-16T08:41:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/\"},\"wordCount\":631,\"image\":{\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i2cat.net\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/7063_1DLL_017-scaled-e1772803447594.jpg\",\"articleSection\":[\"Uncategorized @ca\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/\",\"url\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/\",\"name\":\"El 6GStarLab, el primer laboratori 6G europeu a l'espai, al MWC Barcelona 2026 - i2CAT Research Centre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i2cat.net\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/7063_1DLL_017-scaled-e1772803447594.jpg\",\"datePublished\":\"2026-02-23T13:57:43+00:00\",\"dateModified\":\"2026-03-16T08:41:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/#\\\/schema\\\/person\\\/904ec3612e2fc19f33f02806e8f7f81d\"},\"description\":\"i2CAT va aterrar al MWC Barcelona 2026 per posar a l'abast de l'ecosistema tecnol\u00f2gic i de recerca el 6GStarLab.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i2cat.net\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/7063_1DLL_017-scaled-e1772803447594.jpg\",\"contentUrl\":\"https:\\\/\\\/i2cat.net\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/7063_1DLL_017-scaled-e1772803447594.jpg\",\"width\":1708,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/6gstarlab-mwc-barcelona-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El 6GStarLab, el primer laboratori 6G europeu a l&#8217;espai, al MWC Barcelona 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/\",\"name\":\"i2CAT Research Centre\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/#\\\/schema\\\/person\\\/904ec3612e2fc19f33f02806e8f7f81d\",\"name\":\"M\u00edriam Castillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92b46661059fe77a8c71ff9e65481fb15094612d9147d2b862a643ea32df4b1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92b46661059fe77a8c71ff9e65481fb15094612d9147d2b862a643ea32df4b1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/92b46661059fe77a8c71ff9e65481fb15094612d9147d2b862a643ea32df4b1c?s=96&d=mm&r=g\",\"caption\":\"M\u00edriam Castillo\"},\"url\":\"https:\\\/\\\/i2cat.net\\\/ca\\\/author\\\/miriam-castillo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El 6GStarLab, el primer laboratori 6G europeu a l'espai, al MWC Barcelona 2026 - i2CAT Research Centre","description":"i2CAT va aterrar al MWC Barcelona 2026 per posar a l'abast de l'ecosistema tecnol\u00f2gic i de recerca el 6GStarLab.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/","og_locale":"ca_ES","og_type":"article","og_title":"El 6GStarLab, el primer laboratori 6G europeu a l'espai, al MWC Barcelona 2026 - i2CAT Research Centre","og_description":"i2CAT va aterrar al MWC Barcelona 2026 per posar a l'abast de l'ecosistema tecnol\u00f2gic i de recerca el 6GStarLab.","og_url":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/","og_site_name":"i2CAT Research Centre","article_published_time":"2026-02-23T13:57:43+00:00","article_modified_time":"2026-03-16T08:41:03+00:00","og_image":[{"width":1708,"height":2560,"url":"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/7063_1DLL_017-scaled-e1772803447594.jpg","type":"image\/jpeg"}],"author":"M\u00edriam Castillo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/#article","isPartOf":{"@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/"},"author":{"name":"M\u00edriam Castillo","@id":"https:\/\/i2cat.net\/ca\/#\/schema\/person\/904ec3612e2fc19f33f02806e8f7f81d"},"headline":"El 6GStarLab, el primer laboratori 6G europeu a l&#8217;espai, al MWC Barcelona 2026","datePublished":"2026-02-23T13:57:43+00:00","dateModified":"2026-03-16T08:41:03+00:00","mainEntityOfPage":{"@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/"},"wordCount":631,"image":{"@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/7063_1DLL_017-scaled-e1772803447594.jpg","articleSection":["Uncategorized @ca"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/","url":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/","name":"El 6GStarLab, el primer laboratori 6G europeu a l'espai, al MWC Barcelona 2026 - i2CAT Research Centre","isPartOf":{"@id":"https:\/\/i2cat.net\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/#primaryimage"},"image":{"@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/7063_1DLL_017-scaled-e1772803447594.jpg","datePublished":"2026-02-23T13:57:43+00:00","dateModified":"2026-03-16T08:41:03+00:00","author":{"@id":"https:\/\/i2cat.net\/ca\/#\/schema\/person\/904ec3612e2fc19f33f02806e8f7f81d"},"description":"i2CAT va aterrar al MWC Barcelona 2026 per posar a l'abast de l'ecosistema tecnol\u00f2gic i de recerca el 6GStarLab.","breadcrumb":{"@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/#primaryimage","url":"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/7063_1DLL_017-scaled-e1772803447594.jpg","contentUrl":"https:\/\/i2cat.net\/wp-content\/uploads\/2026\/02\/7063_1DLL_017-scaled-e1772803447594.jpg","width":1708,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/i2cat.net\/ca\/6gstarlab-mwc-barcelona-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/i2cat.net\/ca\/"},{"@type":"ListItem","position":2,"name":"El 6GStarLab, el primer laboratori 6G europeu a l&#8217;espai, al MWC Barcelona 2026"}]},{"@type":"WebSite","@id":"https:\/\/i2cat.net\/ca\/#website","url":"https:\/\/i2cat.net\/ca\/","name":"i2CAT Research Centre","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/i2cat.net\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/i2cat.net\/ca\/#\/schema\/person\/904ec3612e2fc19f33f02806e8f7f81d","name":"M\u00edriam Castillo","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/92b46661059fe77a8c71ff9e65481fb15094612d9147d2b862a643ea32df4b1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/92b46661059fe77a8c71ff9e65481fb15094612d9147d2b862a643ea32df4b1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92b46661059fe77a8c71ff9e65481fb15094612d9147d2b862a643ea32df4b1c?s=96&d=mm&r=g","caption":"M\u00edriam Castillo"},"url":"https:\/\/i2cat.net\/ca\/author\/miriam-castillo\/"}]}},"_links":{"self":[{"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/posts\/20320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/comments?post=20320"}],"version-history":[{"count":7,"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/posts\/20320\/revisions"}],"predecessor-version":[{"id":20503,"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/posts\/20320\/revisions\/20503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/media\/20434"}],"wp:attachment":[{"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/media?parent=20320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/categories?post=20320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/i2cat.net\/ca\/wp-json\/wp\/v2\/tags?post=20320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}